{"id":2122,"date":"2020-11-03T18:39:05","date_gmt":"2020-11-03T17:39:05","guid":{"rendered":"https:\/\/ge-dellbrueck.de\/?p=2122"},"modified":"2025-06-17T12:36:50","modified_gmt":"2025-06-17T10:36:50","slug":"runder-tisch-der-gdm","status":"publish","type":"post","link":"https:\/\/ge-dellbrueck.de\/start\/runder-tisch-der-gdm\/","title":{"rendered":"Runder Tisch der GDM diesmal digital"},"content":{"rendered":"\n<p>Liebe Eltern, liebe Kolleg*innen, liebe SV,<\/p>\n\n\n\n<p>ich m\u00f6chte Sie\/euch ganz herzlich zum <strong>2. RUNDEN TISCH<\/strong>&nbsp;in diesem Schuljahr einladen. Das Treffen findet statt am:             <br><strong>Montag, den 9.11.2020, um 17.00 \u2013 ca. 18.00 Uhr <\/strong><\/p>\n\n\n\n<p><strong>als Jitsi Videokonferenz<\/strong>!<\/p>\n\n\n\n<p>     Sollten Sie Interesse haben, daran teilzunehmen,&nbsp; melden Sie sich unter der E-Mail Adresse der didaktischen Leitung (<a rel=\"noreferrer noopener\" href=\"mailto:dagmar.tadjbach@stadt-koeln.de\" target=\"_blank\">dagmar.tadjbach@stadt-koeln.de) <\/a>an, damit Ihnen\/euch ein Link zur Teilnahme zugeschickt werden kann.     <\/p>\n\n\n\n<p>Ich freue mich auf einen anregenden Austausch.<\/p>\n\n\n\n<p>Herzliche Gr\u00fc\u00dfe<\/p>\n\n\n\n<p>Dagmar Tadjbach<\/p>\n\n\n\n<p>Didaktische Leiterin<\/p>\n\n\n\n<p>Gesamtschule Dellbr\u00fccker Mauspfad<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Liebe Eltern, liebe Kolleg*innen, liebe SV, ich m\u00f6chte Sie\/euch ganz herzlich zum 2. RUNDEN TISCH&nbsp;in diesem Schuljahr einladen. Das Treffen findet statt am: Montag, den 9.11.2020, um 17.00 \u2013 ca. 18.00 Uhr als Jitsi Videokonferenz! Sollten Sie Interesse haben, daran teilzunehmen,&nbsp; melden Sie sich unter der E-Mail Adresse der didaktischen Leitung (dagmar.tadjbach@stadt-koeln.de) an, damit Ihnen\/euch [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":808,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"saved_in_kubio":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2122","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein"],"_links":{"self":[{"href":"https:\/\/ge-dellbrueck.de\/start\/wp-json\/wp\/v2\/posts\/2122","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ge-dellbrueck.de\/start\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ge-dellbrueck.de\/start\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ge-dellbrueck.de\/start\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/ge-dellbrueck.de\/start\/wp-json\/wp\/v2\/comments?post=2122"}],"version-history":[{"count":4,"href":"https:\/\/ge-dellbrueck.de\/start\/wp-json\/wp\/v2\/posts\/2122\/revisions"}],"predecessor-version":[{"id":7639,"href":"https:\/\/ge-dellbrueck.de\/start\/wp-json\/wp\/v2\/posts\/2122\/revisions\/7639"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ge-dellbrueck.de\/start\/wp-json\/wp\/v2\/media\/808"}],"wp:attachment":[{"href":"https:\/\/ge-dellbrueck.de\/start\/wp-json\/wp\/v2\/media?parent=2122"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ge-dellbrueck.de\/start\/wp-json\/wp\/v2\/categories?post=2122"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ge-dellbrueck.de\/start\/wp-json\/wp\/v2\/tags?post=2122"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}