{"id":8030,"date":"2026-01-11T15:38:10","date_gmt":"2026-01-11T14:38:10","guid":{"rendered":"https:\/\/ge-dellbrueck.de\/start\/?p=8030"},"modified":"2026-01-11T15:39:19","modified_gmt":"2026-01-11T14:39:19","slug":"unwetterwarnung-glaettewarnung","status":"publish","type":"post","link":"https:\/\/ge-dellbrueck.de\/start\/unwetterwarnung-glaettewarnung\/","title":{"rendered":"Unwetterwarnung Gl\u00e4ttewarnung"},"content":{"rendered":"\n<p>Liebe Sch\u00fclerinnen und Sch\u00fcler, <\/p>\n\n\n\n<p>Liebe Eltern, <\/p>\n\n\n\n<p>der deutsche Wetterdienst warnt &#8222;Verbreitete Gefahr vor Glatteis mit erheblichen Beeintr\u00e4chtigung auf allen Verkehrswegen&#8220;. Das Ministerium f\u00fcr Schule und Bildung NRW hat &#8222;auf Grundlage des Erlasses &#8222;Regelung zum Unterrichtsausfall und anderen extremen Wetter- Ereignisse&#8220; entschieden, dass kein Unterricht in Pr\u00e4senz am 12. Januar 2026 stattfindet.  <\/p>\n\n\n\n<p>Unsere Schule geht morgen in den Online\/Distanzunterricht nach Stundenplan. <\/p>\n\n\n\n<p>Mit freundlichen Gr\u00fc\u00dfen <\/p>\n\n\n\n<p>Sule Ekemen<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Liebe Sch\u00fclerinnen und Sch\u00fcler, Liebe Eltern, der deutsche Wetterdienst warnt &#8222;Verbreitete Gefahr vor Glatteis mit erheblichen Beeintr\u00e4chtigung auf allen Verkehrswegen&#8220;. Das Ministerium f\u00fcr Schule und Bildung NRW hat &#8222;auf Grundlage des Erlasses &#8222;Regelung zum Unterrichtsausfall und anderen extremen Wetter- Ereignisse&#8220; entschieden, dass kein Unterricht in Pr\u00e4senz am 12. Januar 2026 stattfindet. Unsere Schule geht morgen [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":5822,"comment_status":"closed","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"saved_in_kubio":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-8030","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein"],"_links":{"self":[{"href":"https:\/\/ge-dellbrueck.de\/start\/wp-json\/wp\/v2\/posts\/8030","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ge-dellbrueck.de\/start\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ge-dellbrueck.de\/start\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ge-dellbrueck.de\/start\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/ge-dellbrueck.de\/start\/wp-json\/wp\/v2\/comments?post=8030"}],"version-history":[{"count":3,"href":"https:\/\/ge-dellbrueck.de\/start\/wp-json\/wp\/v2\/posts\/8030\/revisions"}],"predecessor-version":[{"id":8291,"href":"https:\/\/ge-dellbrueck.de\/start\/wp-json\/wp\/v2\/posts\/8030\/revisions\/8291"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ge-dellbrueck.de\/start\/wp-json\/wp\/v2\/media\/5822"}],"wp:attachment":[{"href":"https:\/\/ge-dellbrueck.de\/start\/wp-json\/wp\/v2\/media?parent=8030"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ge-dellbrueck.de\/start\/wp-json\/wp\/v2\/categories?post=8030"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ge-dellbrueck.de\/start\/wp-json\/wp\/v2\/tags?post=8030"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}